{"id":2490,"date":"2019-01-24T00:00:00","date_gmt":"2019-01-23T23:00:00","guid":{"rendered":"https:\/\/web6.karlsruhe.de\/Gemeinderat\/Gruene\/2019\/01\/plaene-fuer-radschulwege-an-weiterfuehrenden-schulen-anfrage-sachverhalt-begruendung\/"},"modified":"2020-08-11T21:58:16","modified_gmt":"2020-08-11T19:58:16","slug":"plaene-fuer-radschulwege-an-weiterfuehrenden-schulen-anfrage-sachverhalt-begruendung","status":"publish","type":"post","link":"https:\/\/web4.karlsruhe.de\/Gemeinderat\/Gruene\/2019\/01\/plaene-fuer-radschulwege-an-weiterfuehrenden-schulen-anfrage-sachverhalt-begruendung\/","title":{"rendered":"Pl\u00e4ne f\u00fcr Radschulwege an weiterf\u00fchrenden Schulen"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Anfrage:<\/h2>\n\n\n\n<ol class=\"wp-block-list\" type=\"1\"><li>F\u00fcr welche weiterf\u00fchrenden Schulen liegen Radschulwegpl\u00e4ne vor? Wann wurden sie erstellt bzw. zuletzt aktualisiert? Welche Erfahrungen wurden bei der Erstellung und Nutzung von Radschulwegpl\u00e4nen an diesen Schulen gemacht?<\/li><li>Inwiefern wurde bei der Erstellung der Radschulwegpl\u00e4ne das webgest\u00fctzte Geoinformationssystem (WebGIS) des Landes Baden-W\u00fcrttemberg genutzt? Welche Erfahrungen wurden mit WebGIS gemacht? Falls WebGIS nicht genutzt wurde: Welche Gr\u00fcnde liegen daf\u00fcr vor?<\/li><li>Bis wann kann f\u00fcr alle weiterf\u00fchrenden Schulen ein Radschulwegplan umgesetzt sein?<\/li><li>Zu welchem Anteil nutzen die Sch\u00fclerinnen und Sch\u00fcler an den jeweiligen weiterf\u00fchrenden Schulen das Fahrrad, um zur Schule zu kommen?<\/li><li>F\u00fcr welche mit dem Rad befahrenen Wege zu weiterf\u00fchrenden Schulen sind besondere Gefahrenpunkte bekannt?<\/li><li>F\u00fcr welche weiterf\u00fchrenden Schulen sieht die Verwaltung die Entwicklung von Radschulwegpl\u00e4nen am dringlichsten an? Welche Kriterien liegen der Einsch\u00e4tzung zugrunde?<\/li><li>Wie sch\u00e4tzt die Verwaltung den potenziellen Lerngewinn f\u00fcr die Sch\u00fclerinnen und Sch\u00fcler durch die Mitwirkung bei der Erstellung von Radschulwegpl\u00e4nen ein, hinsichtlich Verkehrssicherheit wie auch Anwendung von Digitalisierung?<\/li><li>Welche weitere Unterst\u00fctzung durch das Land Baden-W\u00fcrttemberg w\u00fcnscht sich die Verwaltung zur Erreichung des Ziels, f\u00fcr alle weiterf\u00fchrenden Schulen Radschulwegpl\u00e4ne zu entwickeln?<\/li><\/ol>\n\n\n\n<h2 class=\"wp-block-heading\">Sachverhalt\/Begr\u00fcndung<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Im Bericht der Pr\u00fcfkommission zur Zertifizierung \u201eFahrradfreundliche Kommune\u201c wurde f\u00fcr Karlsruhe zur Verkehrssicherheit festgehalten: \u201eIn der Verkehrssicherheit ist Karlsruhe gut aufgestellt. &#8230; Dennoch sieht die Pr\u00fcfkommission Defizite, so z.B. bei der Erstellung der Schulwegpl\u00e4ne. Lediglich 5 von ca. 45 weiterf\u00fchrenden Schulen verf\u00fcgen \u00fcber einen solchen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c Auf Nachfragen der GR\u00dcNEN Fraktion wurde von der Verwaltung mitgeteilt, dass die Erstellung von Radschulwegpl\u00e4nen eine Aufgabe des Landes sei. Eine Recherche zu dem Thema ergab jedoch: \u201eDie Kommunen sind per Erlass der Landesregierung gemeinsam mit den Schulen f\u00fcr die Erstellung der Radschulwegpl\u00e4ne verantwortlich.\u201c<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Aktionserlasse \u201eSicherer Schulweg\u201c des Innenministeriums fordern Schulen und Kommunen j\u00e4hrlich auf, Radschulwegpl\u00e4ne zu erstellen und zu aktualisieren. Laut der Internetseiten des Landes Baden-W\u00fcrttemberg ist in der RadSTRATEGIE Baden-W\u00fcrttemberg das Ziel verankert, bis zum Jahr 2020 f\u00fcr alle Schulen im Land Radschulwege zu schaffen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seit dem Schuljahr 2016\/17 steht landesweit der \u201eRadschulwegplaner Baden &#8211; W\u00fcrttemberg\u201c zur Verf\u00fcgung. \u201eKernelement des neuen Planungsverfahrens ist ein webgest\u00fctztes Geoinformationssystem (WebGIS), das eine Schulwegplanung von Sch\u00fcler*innen f\u00fcr Sch\u00fcler*innen erm\u00f6glicht. Die Grundidee: Sch\u00fclerinnen und Sch\u00fcler wissen selbst am besten, wo ihre Wege sicher sind und wo es noch Verbesserungsbedarf gibt. Daher sollen sie \u2013 in Zusammenarbeit mit Eltern, Lehrkr\u00e4ften und der Schulleitung \u2013 das Radroutennetz im Umfeld ihrer Schule erfassen, beurteilen und Gefahrenpunkte oder Verbesserungsvorschl\u00e4ge in den Radschulwegplan der Kommune einbringen.\u201c<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das WebGIS wurde in einigen Pilotprojekten erprobt, an denen auch Karlsruher Schulen teilnahmen. \u00dcber die gewonnenen Erkenntnisse liegen uns keine Informationen vor. Laut Verkehrsstatistik des Polizeipr\u00e4sidiums Karlsruhe f\u00fcr 2017 wurden in Karlsruhe 39 verungl\u00fcckte radfahrende Kinder bis 13 Jahre der Polizei gemeldet. Die tats\u00e4chliche Zahl der Unf\u00e4lle auf dem Schulweg ist wegen eines hohen Dunkelfeldes sicher deutlich gr\u00f6\u00dfer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nach Ansicht der GR\u00dcNEN Fraktion sollte die Stadt alle M\u00f6glichkeiten ergreifen, Schulwege noch sicherer zu machen. Laut einer Anfrage der GR\u00dcNEN Fraktion im Landtag vom Jahr 2018 haben in Baden-W\u00fcrttemberg 34% der weiterf\u00fchrenden Schulen einen Radschulwegplan&nbsp;(<a href=\"https:\/\/parlis.landtag-bw.de\/parlis\/browse.tt.html?type=&amp;action=qlink&amp;q=BAFO=BASIS%20AND%20VID=V-112043\">https:\/\/parlis.landtag-bw.de\/parlis\/vorgang\/V-112043<\/a>). Die Stadt Karlsruhe liegt mit 5 von 45 (= 11%) damit weit unter dem Durchschnitt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die GR\u00dcNE Fraktion sieht die Entwicklung von Radschulwegen als einen wichtigen Baustein zur Erh\u00f6hung der Sicherheit von Schulwegen. Durch die Mitwirkung bei der Erstellung der Radschulwegpl\u00e4ne werden die Sch\u00fclerinnen und Sch\u00fcler f\u00fcr potenzielle Gefahrenstellen bei der Verkehrssicherheit sensibilisiert. Dar\u00fcber hinaus bietet die Anwendung des webgest\u00fctzten Geoinformationssystems den Schulen die M\u00f6glichkeit, Entwicklungen der Digitalisierung konkret zu nutzen und somit \u00fcbergreifende Kompetenzen zu vermitteln.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Anfrage soll offenlegen, welche Ma\u00dfnahmen in Karlsruhe bisher ergriffen wurden, gemeinsam mit den Schulen, Eltern sowie Sch\u00fclerinnen und Sch\u00fclern Pl\u00e4ne f\u00fcr Radschulwege zu entwickeln und welche Erfahrungen damit gemacht wurden. Gleichzeitig sollen grundlegende Daten und Einsch\u00e4tzungen zur Initiierung weiterer Radschulwegpl\u00e4ne gewonnen werden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Unterzeichnet von:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dr. Ute Leidig, Johannes Honn\u00e9, Renate Rast\u00e4tter, Verena Anlauf,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Christine Weber, Ekkehard Hodapp, Michael Borner<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/web4.karlsruhe.de\/Gemeinderat\/Gruene\/wp-content\/uploads\/2020\/06\/0226_32.pdf\">Stellungnahme der Stadtverwaltung f\u00fcr die Gemeinderatssitzung am 26.02.2019<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Aus dem Gemeinderat vom 26.02.2019:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Antwort der Verwaltung war ern\u00fcchternd: Die Schulen, die dies wollen, erstellen einen solchen Plan und werden \u201egern bei der Erstellung unterst\u00fctzt\u201c. Das w\u00fcnschen wir uns ambitionierter\u2026.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anfrage: F\u00fcr welche weiterf\u00fchrenden Schulen liegen Radschulwegpl\u00e4ne vor? Wann wurden sie erstellt bzw. zuletzt aktualisiert? Welche Erfahrungen wurden bei der Erstellung und Nutzung von Radschulwegpl\u00e4nen an diesen Schulen gemacht? Inwiefern [&hellip;]<\/p>\n","protected":false},"author":-1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[8],"tags":[34,42,48],"class_list":["post-2490","post","type-post","status-publish","format-standard","hentry","category-anfragen","tag-kinder-jugend","tag-mobilitaet","tag-radverkehr"],"_links":{"self":[{"href":"https:\/\/web4.karlsruhe.de\/Gemeinderat\/Gruene\/wp-json\/wp\/v2\/posts\/2490","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web4.karlsruhe.de\/Gemeinderat\/Gruene\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web4.karlsruhe.de\/Gemeinderat\/Gruene\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web4.karlsruhe.de\/Gemeinderat\/Gruene\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/web4.karlsruhe.de\/Gemeinderat\/Gruene\/wp-json\/wp\/v2\/comments?post=2490"}],"version-history":[{"count":10,"href":"https:\/\/web4.karlsruhe.de\/Gemeinderat\/Gruene\/wp-json\/wp\/v2\/posts\/2490\/revisions"}],"predecessor-version":[{"id":10087,"href":"https:\/\/web4.karlsruhe.de\/Gemeinderat\/Gruene\/wp-json\/wp\/v2\/posts\/2490\/revisions\/10087"}],"wp:attachment":[{"href":"https:\/\/web4.karlsruhe.de\/Gemeinderat\/Gruene\/wp-json\/wp\/v2\/media?parent=2490"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web4.karlsruhe.de\/Gemeinderat\/Gruene\/wp-json\/wp\/v2\/categories?post=2490"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web4.karlsruhe.de\/Gemeinderat\/Gruene\/wp-json\/wp\/v2\/tags?post=2490"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}