{"id":14635,"date":"2022-12-13T15:59:03","date_gmt":"2022-12-13T14:59:03","guid":{"rendered":"https:\/\/web6.karlsruhe.de\/Gemeinderat\/Gruene\/?p=14635"},"modified":"2025-03-03T18:27:58","modified_gmt":"2025-03-03T17:27:58","slug":"mehr-baumarten-und-mehr-baeume-in-der-kaiserstrasse","status":"publish","type":"post","link":"https:\/\/web4.karlsruhe.de\/Gemeinderat\/Gruene\/2022\/12\/mehr-baumarten-und-mehr-baeume-in-der-kaiserstrasse\/","title":{"rendered":"Mehr Baumarten und mehr B\u00e4ume in der Kaiserstra\u00dfe"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Erg\u00e4nzungsantrag<strong> <\/strong>zu TOP 9 der Gemeinderatssitzung am 20. Dez. 2022: Neugestaltung Kaiserstra\u00dfe<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<ol class=\"wp-block-list\" type=\"1\">\n<li>Mindestens eine weitere klimastabile Baumart wird alternierend oder abschnittsweise wechselnd mit den Z\u00fcrgelb\u00e4umen in der Kaiserstra\u00dfe gepflanzt.<\/li>\n\n\n\n<li>Um einen m\u00f6glichst durchgehenden Schattenwurf zu erhalten, wird f\u00fcr die weiteren Bauabschnitte gepr\u00fcft, wo zus\u00e4tzliche Baumstandorte m\u00f6glich sind.<\/li>\n<\/ol>\n\n\n\n<h3 class=\"wp-block-heading\">Begr\u00fcndung\/Sachverhalt: <\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Namhafte Baumexpert*innen haben darauf hingewiesen, dass auch beim Z\u00fcrgelbaum mittelfristig Sch\u00e4dlinge auftreten k\u00f6nnten. Deshalb wird allgemein geraten, vorsorglich nicht nur auf eine Baumart zu setzen, sondern mindestens eine weitere Baumart vorzusehen. Dadurch w\u00fcrde das Risiko des Totalausfalls aller B\u00e4ume verringert, so dass gro\u00dfe B\u00e4ume verbleiben, auch wenn ggf. Ersatzpflanzungen f\u00fcr eine Baumart n\u00f6tig sein sollten. Aus Sicht der gr\u00fcnen Fraktion w\u00e4re es sinnvoller, die Baumarten alternierend zu pflanzen, sowohl wegen der dadurch m\u00f6glichen Abst\u00e4nde zwischen den Z\u00fcrgelb\u00e4umen, als auch aus gestalterischen Gr\u00fcnden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au\u00dferdem sollte angesichts der steigenden Hitzeperioden darauf geachtet werden, dass der Schattenwurf m\u00f6glichst durchgehend ist, wenn die neuen B\u00e4ume ausgewachsen sind. Dazu sollten so viele Baumstandorte wie m\u00f6glich eingeplant werden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wegen der kurzen Vorlaufzeit bis zum Beginn des ersten Bauabschnitts k\u00f6nnten ggf. zun\u00e4chst die beiden Gruppen von je zehn Z\u00fcrgelb\u00e4umen gepflanzt werden. Ab dem n\u00e4chsten Bauabschnitt sollte aber die Planung von zus\u00e4tzlichen B\u00e4umen greifen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Unterzeichnet von:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Renate Rast\u00e4tter\u00a0\u00a0\u00a0\u00a0\u00a0 Johannes Honn\u00e9\u00a0\u00a0\u00a0 Christina Bischoff\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0 Aljoscha L\u00f6ffler<br>Benjamin Bauer\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Verena Anlauf\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Dr. Clemens Cremer\u00a0\u00a0\u00a0 Jorinda Fahringer<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In der <a href=\"https:\/\/web4.karlsruhe.de\/Gemeinderat\/Gruene\/2022\/11\/fragen-und-antworten-zur-umgestaltung-der-kaiserstrasse-und-zu-den-dortigen-platanen\/\">Debatte am 20.12.2022<\/a> wurde dieser Vorschlag <a href=\"https:\/\/web1.karlsruhe.de\/ris\/oparl\/bodies\/0001\/downloadfiles\/00643487.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">von der Verwaltung<\/a> und im Gemeinderat breit unterst\u00fctzt und wird weiter verfolgt.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Erg\u00e4nzungsantrag zu TOP 9 der Gemeinderatssitzung am 20. Dez. 2022: Neugestaltung Kaiserstra\u00dfe Begr\u00fcndung\/Sachverhalt: Namhafte Baumexpert*innen haben darauf hingewiesen, dass auch beim Z\u00fcrgelbaum mittelfristig Sch\u00e4dlinge auftreten k\u00f6nnten. Deshalb wird allgemein geraten, [&hellip;]<\/p>\n","protected":false},"author":-1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[9],"tags":[35,43,55,59],"class_list":["post-14635","post","type-post","status-publish","format-standard","hentry","category-antraege-anfragen","tag-klimaschutz","tag-naturschutz","tag-stadtentwicklung","tag-umweltschutz"],"_links":{"self":[{"href":"https:\/\/web4.karlsruhe.de\/Gemeinderat\/Gruene\/wp-json\/wp\/v2\/posts\/14635","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web4.karlsruhe.de\/Gemeinderat\/Gruene\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web4.karlsruhe.de\/Gemeinderat\/Gruene\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web4.karlsruhe.de\/Gemeinderat\/Gruene\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/web4.karlsruhe.de\/Gemeinderat\/Gruene\/wp-json\/wp\/v2\/comments?post=14635"}],"version-history":[{"count":3,"href":"https:\/\/web4.karlsruhe.de\/Gemeinderat\/Gruene\/wp-json\/wp\/v2\/posts\/14635\/revisions"}],"predecessor-version":[{"id":14771,"href":"https:\/\/web4.karlsruhe.de\/Gemeinderat\/Gruene\/wp-json\/wp\/v2\/posts\/14635\/revisions\/14771"}],"wp:attachment":[{"href":"https:\/\/web4.karlsruhe.de\/Gemeinderat\/Gruene\/wp-json\/wp\/v2\/media?parent=14635"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web4.karlsruhe.de\/Gemeinderat\/Gruene\/wp-json\/wp\/v2\/categories?post=14635"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web4.karlsruhe.de\/Gemeinderat\/Gruene\/wp-json\/wp\/v2\/tags?post=14635"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}