{"id":13216,"date":"2022-06-11T13:54:00","date_gmt":"2022-06-11T11:54:00","guid":{"rendered":"https:\/\/web6.karlsruhe.de\/Gemeinderat\/Gruene\/?p=13216"},"modified":"2025-03-03T17:27:18","modified_gmt":"2025-03-03T16:27:18","slug":"schule-und-kita-in-der-kommunalpolitik","status":"publish","type":"post","link":"https:\/\/web4.karlsruhe.de\/Gemeinderat\/Gruene\/2022\/06\/schule-und-kita-in-der-kommunalpolitik\/","title":{"rendered":"Schule und Kita in der Kommunalpolitik"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Die untenstehende Pr\u00e4sentation enth\u00e4lt Daten und Fakten zu Karlsruher Schulen und Kitas. Sie gibt eine \u00dcbersicht zu Themen wie der Betreuungssituation und Beitragssystematik Karlsruher Kitas oder dem Stand der Digitalisierung und Herausforderungen der Pandemie in Karlsruher Schulen. Au\u00dferdem findet sich dort eine Zusammenfassung gr\u00fcner Initiativen im Bereich Schule und Kita.<\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/web4.karlsruhe.de\/Gemeinderat\/Gruene\/wp-content\/uploads\/2022\/06\/Schule-Kita-in-der-Kommunalpolitik.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Einbettung von Einbettung von Schule-Kita-in-der-Kommunalpolitik..\"><\/object><a id=\"wp-block-file--media-3b7d498b-7172-45a5-9814-a10732a15458\" href=\"https:\/\/web4.karlsruhe.de\/Gemeinderat\/Gruene\/wp-content\/uploads\/2022\/06\/Schule-Kita-in-der-Kommunalpolitik.pdf\">Schule-Kita-in-der-Kommunalpolitik<\/a><a href=\"https:\/\/web4.karlsruhe.de\/Gemeinderat\/Gruene\/wp-content\/uploads\/2022\/06\/Schule-Kita-in-der-Kommunalpolitik.pdf\" class=\"wp-block-file__button\" download aria-describedby=\"wp-block-file--media-3b7d498b-7172-45a5-9814-a10732a15458\">Herunterladen<\/a><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die untenstehende Pr\u00e4sentation enth\u00e4lt Daten und Fakten zu Karlsruher Schulen und Kitas. Sie gibt eine \u00dcbersicht zu Themen wie der Betreuungssituation und Beitragssystematik Karlsruher Kitas oder dem Stand der Digitalisierung [&hellip;]<\/p>\n","protected":false},"author":-1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1],"tags":[17,24,34],"class_list":["post-13216","post","type-post","status-publish","format-standard","hentry","category-aktuelles","tag-bildung","tag-familien","tag-kinder-jugend"],"_links":{"self":[{"href":"https:\/\/web4.karlsruhe.de\/Gemeinderat\/Gruene\/wp-json\/wp\/v2\/posts\/13216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web4.karlsruhe.de\/Gemeinderat\/Gruene\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web4.karlsruhe.de\/Gemeinderat\/Gruene\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web4.karlsruhe.de\/Gemeinderat\/Gruene\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/web4.karlsruhe.de\/Gemeinderat\/Gruene\/wp-json\/wp\/v2\/comments?post=13216"}],"version-history":[{"count":8,"href":"https:\/\/web4.karlsruhe.de\/Gemeinderat\/Gruene\/wp-json\/wp\/v2\/posts\/13216\/revisions"}],"predecessor-version":[{"id":17650,"href":"https:\/\/web4.karlsruhe.de\/Gemeinderat\/Gruene\/wp-json\/wp\/v2\/posts\/13216\/revisions\/17650"}],"wp:attachment":[{"href":"https:\/\/web4.karlsruhe.de\/Gemeinderat\/Gruene\/wp-json\/wp\/v2\/media?parent=13216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web4.karlsruhe.de\/Gemeinderat\/Gruene\/wp-json\/wp\/v2\/categories?post=13216"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web4.karlsruhe.de\/Gemeinderat\/Gruene\/wp-json\/wp\/v2\/tags?post=13216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}